{"id":177,"date":"2022-09-19T12:21:00","date_gmt":"2022-09-19T12:21:00","guid":{"rendered":"http:\/\/golfmad.org\/blog\/?p=177"},"modified":"2022-09-17T12:22:21","modified_gmt":"2022-09-17T12:22:21","slug":"golf-turkei-und-golftourismus-in-der-turkei","status":"publish","type":"post","link":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/","title":{"rendered":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei"},"content":{"rendered":"\n<p>Unser Land ist gekommen, um Weltklasse-Golfturniere auszurichten. Die Challenge Tour, die erste Etappe der europ\u00e4ischen professionellen Golftour, wurde 2010 in unserem Land mit 22 L\u00e4ndern organisiert, und die IGTM 2011 (International Golf Travel Market-International Golf Tourism Fair), die als wichtigste Veranstaltung der Welt gilt Welt des Golftourismus, fand vom 14. bis 17. November 2011 in Belek statt. durchgef\u00fchrt wurde. Die Golfweltmeisterschaft fand 2012 in unserem Land statt und diese Meisterschaft wurde von Belek ausgerichtet, das 2008 die Auszeichnung f\u00fcr die beste Golfdestination in Europa erhielt. Die t\u00fcrkische Etappe der World Corporate Golf Challenge fand vom 5. bis 7. April 2013 in Belek statt. Das Turkish Airlines Open Golf Tournament, die erste Etappe der Finalserie der European Tour, fand vom 3. bis 6. November 2016 in Belek statt und 78 Golfer aus 20 L\u00e4ndern nahmen an dem Turnier teil. 2018 wurden in der T\u00fcrkei insgesamt 108 nationale und internationale Golfturniere organisiert.<\/p>\n\n\n\n<p>In den Provinzen Antalya, Ayd\u0131n, Mu\u011fla, Mersin und Nev\u015fehir sind 49 Golfpl\u00e4tze als <strong>Golf T\u00fcrkei<\/strong> innerhalb der Kultur- und Tourismus-Erhaltungs- und Entwicklungszone, des Tourismuszentrums und des Tourismusgebiets geplant, und eine Bettenkapazit\u00e4t von etwa 35.000 wird angestrebt.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#Wo_wird_Golftourismus_in_der_Turkei_betrieben\" >Wo wird Golftourismus in der T\u00fcrkei betrieben?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#Wie_viel_kostet_Golf_spielen\" >Wie viel kostet Golf spielen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#Welches_ist_das_beruhmteste_Golfturnier\" >Welches ist das ber\u00fchmteste Golfturnier?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wo_wird_Golftourismus_in_der_Turkei_betrieben\"><\/span>Wo wird Golftourismus in der T\u00fcrkei betrieben?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Golfpl\u00e4tze und -anlagen in Mugla und Istanbul schaffen ein einzigartiges Potenzial f\u00fcr den Golftourismus als <strong>Golf T\u00fcrkei<\/strong>. Es veranstaltet auch internationale Turniere.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wie_viel_kostet_Golf_spielen\"><\/span>Wie viel kostet Golf spielen?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>In der T\u00fcrkei variiert er zwischen 2.500 und 40.000 Lire pro Jahr. Die Stundengeb\u00fchr f\u00fcr Golfkurse betr\u00e4gt 100-150 Lira. Die Stundens\u00e4tze f\u00fcr Gruppenunterricht betragen nur 40 Lire pro Person.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Welches_ist_das_beruhmteste_Golfturnier\"><\/span>Welches ist das ber\u00fchmteste Golfturnier?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Das Masters Tournament ist ein Golfturnier, das 1934 ins Leben gerufen wurde. Der erste Champion des Turniers ist Horton Smith. Der letzte Tag des Masters, des ersten der vier gro\u00dfen Turniere, f\u00e4llt auf den zweiten Sonntag im April. Es ist das einzige gro\u00dfe Turnier, das jedes Jahr am selben Ort (Augusta National Golf Club) stattfindet. Snag Golf ist das perfekte Anf\u00e4ngertraining f\u00fcr Kinder im Alter von 3 bis 12 Jahren, um Golf zu lernen. Das wichtigste Merkmal, das er von einem Sporttraining erwartet, ist, dass die Branche spa\u00df- und spielorientiert ist. Eine der \u00e4ltesten Golforganisationen, Schottland, St. Laut einem Sprecher des Royal and Ancient Golf Club in St. Andrews \u201egibt es viele alte Schl\u00e4ger-und-Ball-Spiele, aber das heutige 18-Loch-Golf hat seinen Ursprung sicherlich in Schottland, und daran gibt es keinen Zweifel \u2026\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Land ist gekommen, um Weltklasse-Golfturniere auszurichten. Die Challenge Tour, die erste Etappe der europ\u00e4ischen professionellen Golftour, wurde 2010 in unserem Land mit 22 L\u00e4ndern organisiert, und die IGTM 2011 (International Golf Travel Market-International Golf Tourism Fair), die als wichtigste Veranstaltung der Welt gilt Welt des Golftourismus, fand vom 14. bis 17. November 2011 in Belek statt. durchgef\u00fchrt wurde. Die Golfweltmeisterschaft fand 2012 in unserem Land statt und diese Meisterschaft wurde von Belek ausgerichtet, das&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[78,75,77,76],"class_list":["post-177","post","type-post","status-publish","format-standard","hentry","category-golfmad","tag-golf-spielen","tag-golf-turkei","tag-golftourismus","tag-golfturnier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei - Golf Mad<\/title>\n<meta name=\"description\" content=\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei Golf Mad, Golf in Belek, T\u00fcrkiye, Turkey\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei - Golf Mad\" \/>\n<meta property=\"og:description\" content=\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei Golf Mad, Golf in Belek, T\u00fcrkiye, Turkey\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\" \/>\n<meta property=\"og:site_name\" content=\"Golf Mad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/golfmadtravel\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-19T12:21:00+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"http:\/\/golfmad.org\/blog\/#\/schema\/person\/333f9723decc685673405097840867a1\"},\"headline\":\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei\",\"datePublished\":\"2022-09-19T12:21:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"http:\/\/golfmad.org\/blog\/#organization\"},\"keywords\":[\"Golf spielen\",\"Golf T\u00fcrkei\",\"Golftourismus\",\"Golfturnier\"],\"articleSection\":[\"Golf Mad\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\",\"url\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\",\"name\":\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei - Golf Mad\",\"isPartOf\":{\"@id\":\"http:\/\/golfmad.org\/blog\/#website\"},\"datePublished\":\"2022-09-19T12:21:00+00:00\",\"description\":\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei Golf Mad, Golf in Belek, T\u00fcrkiye, Turkey\",\"breadcrumb\":{\"@id\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/golfmad.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/golfmad.org\/blog\/#website\",\"url\":\"http:\/\/golfmad.org\/blog\/\",\"name\":\"Golf Mad Travel & Events\",\"description\":\"Travel &amp; Events Official Blog\",\"publisher\":{\"@id\":\"http:\/\/golfmad.org\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/golfmad.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/golfmad.org\/blog\/#organization\",\"name\":\"Golf Mad Travel & Events\",\"url\":\"http:\/\/golfmad.org\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/golfmad.org\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/golfmad.org\/blog\/wp-content\/uploads\/2022\/02\/cropped-GolfMad-Academy-LOGO-1-e1645377638669.png\",\"contentUrl\":\"https:\/\/golfmad.org\/blog\/wp-content\/uploads\/2022\/02\/cropped-GolfMad-Academy-LOGO-1-e1645377638669.png\",\"width\":160,\"height\":139,\"caption\":\"Golf Mad Travel & Events\"},\"image\":{\"@id\":\"http:\/\/golfmad.org\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/golfmadtravel\",\"https:\/\/www.instagram.com\/golfmadtravel\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/golfmad.org\/blog\/#\/schema\/person\/333f9723decc685673405097840867a1\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/golfmad.org\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/golfmad.org\/blog\/wp-content\/litespeed\/avatar\/d500f1a6778025ca9804df2f90f83a46.jpg?ver=1783713536\",\"contentUrl\":\"https:\/\/golfmad.org\/blog\/wp-content\/litespeed\/avatar\/d500f1a6778025ca9804df2f90f83a46.jpg?ver=1783713536\",\"caption\":\"admin\"},\"url\":\"https:\/\/golfmad.org\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei - Golf Mad","description":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei Golf Mad, Golf in Belek, T\u00fcrkiye, Turkey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/","og_locale":"en_US","og_type":"article","og_title":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei - Golf Mad","og_description":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei Golf Mad, Golf in Belek, T\u00fcrkiye, Turkey","og_url":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/","og_site_name":"Golf Mad","article_publisher":"https:\/\/www.facebook.com\/golfmadtravel","article_published_time":"2022-09-19T12:21:00+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#article","isPartOf":{"@id":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/"},"author":{"name":"admin","@id":"http:\/\/golfmad.org\/blog\/#\/schema\/person\/333f9723decc685673405097840867a1"},"headline":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei","datePublished":"2022-09-19T12:21:00+00:00","mainEntityOfPage":{"@id":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/"},"wordCount":398,"publisher":{"@id":"http:\/\/golfmad.org\/blog\/#organization"},"keywords":["Golf spielen","Golf T\u00fcrkei","Golftourismus","Golfturnier"],"articleSection":["Golf Mad"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/","url":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/","name":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei - Golf Mad","isPartOf":{"@id":"http:\/\/golfmad.org\/blog\/#website"},"datePublished":"2022-09-19T12:21:00+00:00","description":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei Golf Mad, Golf in Belek, T\u00fcrkiye, Turkey","breadcrumb":{"@id":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/golfmad.org\/blog\/golf-turkei-und-golftourismus-in-der-turkei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/golfmad.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Golf T\u00fcrkei und Golftourismus in der T\u00fcrkei"}]},{"@type":"WebSite","@id":"http:\/\/golfmad.org\/blog\/#website","url":"http:\/\/golfmad.org\/blog\/","name":"Golf Mad Travel & Events","description":"Travel &amp; Events Official Blog","publisher":{"@id":"http:\/\/golfmad.org\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/golfmad.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/golfmad.org\/blog\/#organization","name":"Golf Mad Travel & Events","url":"http:\/\/golfmad.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/golfmad.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/golfmad.org\/blog\/wp-content\/uploads\/2022\/02\/cropped-GolfMad-Academy-LOGO-1-e1645377638669.png","contentUrl":"https:\/\/golfmad.org\/blog\/wp-content\/uploads\/2022\/02\/cropped-GolfMad-Academy-LOGO-1-e1645377638669.png","width":160,"height":139,"caption":"Golf Mad Travel & Events"},"image":{"@id":"http:\/\/golfmad.org\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/golfmadtravel","https:\/\/www.instagram.com\/golfmadtravel"]},{"@type":"Person","@id":"http:\/\/golfmad.org\/blog\/#\/schema\/person\/333f9723decc685673405097840867a1","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/golfmad.org\/blog\/#\/schema\/person\/image\/","url":"https:\/\/golfmad.org\/blog\/wp-content\/litespeed\/avatar\/d500f1a6778025ca9804df2f90f83a46.jpg?ver=1783713536","contentUrl":"https:\/\/golfmad.org\/blog\/wp-content\/litespeed\/avatar\/d500f1a6778025ca9804df2f90f83a46.jpg?ver=1783713536","caption":"admin"},"url":"https:\/\/golfmad.org\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/posts\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":1,"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/posts\/177\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/posts\/177\/revisions\/178"}],"wp:attachment":[{"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/categories?post=177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfmad.org\/blog\/wp-json\/wp\/v2\/tags?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}